{"id":22275,"date":"2020-03-15T09:52:14","date_gmt":"2020-03-15T09:52:14","guid":{"rendered":"https:\/\/salumeriaittica.org\/prodotto\/salami-de-poulpe-soppressata\/"},"modified":"2020-03-15T09:52:14","modified_gmt":"2020-03-15T09:52:14","slug":"salami-de-poulpe-soppressata","status":"publish","type":"product","link":"https:\/\/salumeriaittica.org\/fr\/prodotto\/salami-de-poulpe-soppressata\/","title":{"rendered":"Salami de poulpe soppressata"},"content":{"rendered":"<div>\n<h1>Salami de poulpe soppressata<\/h1>\n<p>Le nom d\u00e9sign\u00e9 pour ce plat d\u00e9licieux, et celui qui l\u2019appelle le plus souvent dans les menus des restaurants, est le carpaccio de pieuvre.<br \/>\nPeut-\u00eatre moins appropri\u00e9, mais en r\u00e9f\u00e9rence au nom du protagoniste incontest\u00e9 de cette recette, il devrait \u00eatre appel\u00e9 \u00ab Octopus soppressata \u00bb.<br \/>\nQuoi qu\u2019il en soit, clarifions d\u2019abord que dans ce plat il y a ind\u00e9niablement une pr\u00e9sentation originale et efficace.<br \/>\nCe n\u2019est rien d\u2019autre qu\u2019une renaissance de la c\u00e9l\u00e8bre et universellement appr\u00e9ci\u00e9e soppressata toscane au porc.<br \/>\nC\u2019est un plat d\u2019\u00e9t\u00e9 froid, \u00e0 proposer en entr\u00e9e accompagn\u00e9 d\u2019un filet d\u2019huile d\u2019olive extra vierge.<\/p>\n<\/div>\n<div>\n<ul>\n<li>Teneur \u00e9lev\u00e9e en prot\u00e9ines Environ 34 %<\/li>\n<li>Teneur en graisses r\u00e9duite (seulement 1,2 %)<\/li>\n<li>Il contient des Om\u00e9ga 3 et 6, pr\u00e9cieux alli\u00e9s de notre corps<\/li>\n<li>Elle contient de nombreux min\u00e9raux tels que le potassium, le s\u00e9l\u00e9nium et le phosphore<\/li>\n<li>Il existe aussi des vitamines B<\/li>\n<li>Id\u00e9al dans les r\u00e9gimes pauvres en calories<\/li>\n<li>Sans gluten<\/li>\n<li>Sans lactose<\/li>\n<li>Incroyablement bon et l\u00e9ger, id\u00e9al pour les r\u00e9gimes pauvres en calories.<\/li>\n<li>Adapt\u00e9 aux sportifs et aux passionn\u00e9s de sant\u00e9<\/li>\n<\/ul>\n<\/div>\n<div>\n<p>et qui conserve toute la l\u00e9g\u00e8ret\u00e9 typique du poisson cuit mais avec la garantie alimentaire maximale.<\/p>\n<p><a href=\"https:\/\/salumeriaittica.org\/fr\/categoria-prodotto\/carpaccio\/\">https:\/\/salumeriaittica.org\/categoria-prodotto\/carpacci\/<\/a><\/p>\n<p><strong>Emballage : <\/strong>emballage sous vide<\/p>\n<p><strong>Poids : Choisissez parmi les poids disponibles<\/strong><\/p>\n<p><strong>Dur\u00e9e : 40<\/strong> jours<\/p>\n<p><strong>Disponibilit\u00e9 : <\/strong>toute l\u2019ann\u00e9e<\/p>\n<ul>\n<li>Prix \u20ac\/kg 76,16\n<p>Ingr\u00e9dients : <strong>PIEUVRE cuite<\/strong> (Octopus vulgaris), <strong>GEL\u00c9E de poisson<\/strong>, \u00e9pices, ail, sel Volterra, sucre.<\/li>\n<\/ul>\n<p>ALLERG\u00c8NES :<strong> MOLLUSQUES<br \/>\n<\/strong>Peuvent contenir des traces de :<strong> POISSONS, NOIX, CRUSTAC\u00c9S<\/strong><\/p>\n<div class=\"tabella-nutrizionale-container\" style=\"max-width: 400px; margin: 20px 0; font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Helvetica, Arial, sans-serif; border: 1px solid #e0e0e0; border-radius: 8px; overflow: hidden; box-shadow: 0 2px 4px rgba(0,0,0,0.05);\">\n<div style=\"background-color: #f8f9fa; padding: 15px; border-bottom: 2px solid #222;\">\n<h3 style=\"margin: 0; font-size: 18px; font-weight: bold; uppercase; color: #222;\">Valeurs nutritionnelles<\/h3>\n<p style=\"margin: 5px 0 0 0; font-size: 13px; color: #666; font-style: italic;\">Valeurs moyennes pour 100g de produit<\/p>\n<\/div>\n<table style=\"width: 100%; border-collapse: collapse; margin: 0; background: #fff;\">\n<tbody>\n<tr style=\"border-bottom: 1px solid #eeeeee;\">\nValeur <\/p>\n<td style=\"padding: 12px 15px; font-weight: 600; color: #222; font-size: 14px;\">\u00e9nerg\u00e9tique<\/td>\n<td style=\"padding: 12px 15px; text-align: right; font-weight: 600; color: #222; font-size: 14px;\">649 kJ \/ 155 kcal<\/td>\n<\/tr>\n<tr style=\"border-bottom: 1px solid #eeeeee;\">\n<td style=\"padding: 12px 15px; font-weight: 600; color: #222; font-size: 14px;\">Gras<\/td>\n<td style=\"padding: 12px 15px; text-align: right; color: #333; font-size: 14px;\">1 g<\/td>\n<\/tr>\n<tr style=\"border-bottom: 1px solid #eeeeee; background-color: #fafafa;\">\n<td style=\"padding: 10px 15px 10px 30px; color: #666; font-size: 13px;\"><em>dont Acides gras satur\u00e9s<\/em><\/td>\n<td style=\"padding: 10px 15px; text-align: right; color: #666; font-size: 13px;\">0,05 g<\/td>\n<\/tr>\n<tr style=\"border-bottom: 1px solid #eeeeee;\">\n<td style=\"padding: 12px 15px; font-weight: 600; color: #222; font-size: 14px;\">Glucides<\/td>\n<td style=\"padding: 12px 15px; text-align: right; color: #333; font-size: 14px;\">2 g<\/td>\n<\/tr>\n<tr style=\"border-bottom: 1px solid #eeeeee; background-color: #fafafa;\">\n<td style=\"padding: 10px 15px 10px 30px; color: #666; font-size: 13px;\"><em>dont sucres<\/em><\/td>\n<td style=\"padding: 10px 15px; text-align: right; color: #666; font-size: 13px;\">0,5 g<\/td>\n<\/tr>\n<tr style=\"border-bottom: 1px solid #eeeeee;\">\n<td style=\"padding: 12px 15px; font-weight: 600; color: #222; font-size: 14px;\">Prot\u00e9ines<\/td>\n<td style=\"padding: 12px 15px; text-align: right; color: #333; font-size: 14px;\">34,4 g<\/td>\n<\/tr>\n<tr style=\"border-bottom: 1px solid #222;\">\n<td style=\"padding: 12px 15px; font-weight: 600; color: #222; font-size: 14px;\">Sel<\/td>\n<td style=\"padding: 12px 15px; text-align: right; color: #333; font-size: 14px;\">0,9 g<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<h2>La saveur et <a href=\"https:\/\/salumidimare.com\/prodotti\/polpo\/carpaccio-di-polpo-salame-di-polpo\/\">l\u2019ar\u00f4me de la pieuvre soppressata<\/a><\/h2>\n<p>Coupez-la finement avec un couteau ou, mieux encore, avec un trancheur, comme s\u2019il s\u2019agissait d\u2019un salami et posez-la sur une assiette de service.<br \/>\nEnsuite, pr\u00e9parez la citronette qui servira \u00e0 aromatiser la pieuvre, \u00e9mulsifiant du jus de citron, un peu de jus d\u2019orange, de l\u2019huile d\u2019olive et une pinc\u00e9e de sel.<br \/>\nDisposez les tranches de poulpe sur une assiette de service, saupoudrez-les de persil hach\u00e9 avec un peu d\u2019ail, puis assaisonnez la soppressata sur l\u2019assiette avec la citronette.<br \/>\nGarnissez le carpaccio de pieuvre avec des tranches ou quartiers de citron et des brins de persil.<\/p>\n<div class=\"mceTemp\"><\/div>\n<p><a href=\"https:\/\/salumeriaittica.org\/fr\/?attachment_id=6902\" rel=\"attachment wp-att-6902\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-6902 size-medium\" src=\"https:\/\/salumeriaittica.org\/wp-content\/uploads\/2020\/03\/soppressata-di-polpo1-300x224.jpg\" alt=\"\" width=\"300\" height=\"224\" srcset=\"https:\/\/salumeriaittica.org\/wp-content\/uploads\/2020\/03\/soppressata-di-polpo1-300x224.jpg 300w, https:\/\/salumeriaittica.org\/wp-content\/uploads\/2020\/03\/soppressata-di-polpo1-500x373.jpg 500w, https:\/\/salumeriaittica.org\/wp-content\/uploads\/2020\/03\/soppressata-di-polpo1-768x573.jpg 768w, https:\/\/salumeriaittica.org\/wp-content\/uploads\/2020\/03\/soppressata-di-polpo1-600x448.jpg 600w, https:\/\/salumeriaittica.org\/wp-content\/uploads\/2020\/03\/soppressata-di-polpo1.jpg 880w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le nom d\u00e9sign\u00e9 pour ce plat d\u00e9licieux, et celui qui l\u2019utilise le plus souvent dans les menus des restaurants, est le carpaccio de pieuvre.<br \/>\n Peut-\u00eatre moins pr\u00e9cis\u00e9, mais en r\u00e9f\u00e9rence au nom du protagoniste incontest\u00e9 de cette recette, il devrait \u00eatre indiqu\u00e9 comme \u00ab Octopus soppressata \u00bb.<br \/>\n Quoi qu\u2019il en soit, clarifions d\u2019abord que ce plat pr\u00e9sente ind\u00e9niablement une pr\u00e9sentation originale et efficace.<br \/>\n Ce n\u2019est rien d\u2019autre qu\u2019une renaissance de la c\u00e9l\u00e8bre et universellement appr\u00e9ci\u00e9e soppressata de porc toscane.<br \/>\n C\u2019est un plat froid d\u2019\u00e9t\u00e9, \u00e0 proposer en entr\u00e9e accompagn\u00e9 d\u2019un filet d\u2019huile d\u2019olive extra vierge.<br \/>\n Prix \u20ac\/kg 79,00<\/p>\n","protected":false},"featured_media":22286,"comment_status":"open","ping_status":"closed","template":"","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","om_disable_all_campaigns":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"slim_seo":{"title":"Soppressata Octopus Salami","description":"La Soppressta di Octopus ou salami de poulpe est fabriqu\u00e9e exclusivement avec des poulpes s\u00e9lectionn\u00e9es pour leur origine m\u00e9diterran\u00e9enne et de grande taille, elles sont coup\u00e9es, cuites et press\u00e9es manuellement ; ce qui permet d\u2019obtenir une saucisse tr\u00e8s compacte, sans conservateurs ni colorants"}},"product_brand":[],"product_cat":[3489,1392,1397,3579],"product_tag":[3849,1638,3511,3848,2242,2243,3791],"class_list":["post-22275","product","type-product","status-publish","has-post-thumbnail","product_cat-carpaccio","product_cat-sans-gluten","product_cat-sans-lactose","product_cat-viandes-cuites","product_tag-carpaccio-de-pieuvre","product_tag-epicerie-de-poisson","product_tag-pieuvre","product_tag-poulpe-soppressata","product_tag-produits-sans-gluten","product_tag-produits-sans-lactose","product_tag-salami-de-pieuvre","yith_product_brand-viandes-salees-de-fruits-de-mer","first","instock","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/salumeriaittica.org\/fr\/wp-json\/wp\/v2\/product\/22275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salumeriaittica.org\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/salumeriaittica.org\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/salumeriaittica.org\/fr\/wp-json\/wp\/v2\/comments?post=22275"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/salumeriaittica.org\/fr\/wp-json\/wp\/v2\/media\/22286"}],"wp:attachment":[{"href":"https:\/\/salumeriaittica.org\/fr\/wp-json\/wp\/v2\/media?parent=22275"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/salumeriaittica.org\/fr\/wp-json\/wp\/v2\/product_brand?post=22275"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/salumeriaittica.org\/fr\/wp-json\/wp\/v2\/product_cat?post=22275"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/salumeriaittica.org\/fr\/wp-json\/wp\/v2\/product_tag?post=22275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}