{"id":22129,"date":"2020-11-29T09:18:09","date_gmt":"2020-11-29T09:18:09","guid":{"rendered":"https:\/\/salumeriaittica.org\/prodotto\/jambon-au-thon-assaisonne\/"},"modified":"2020-11-29T09:18:09","modified_gmt":"2020-11-29T09:18:09","slug":"jambon-au-thon-assaisonne","status":"publish","type":"product","link":"https:\/\/salumeriaittica.org\/fr\/prodotto\/jambon-au-thon-assaisonne\/","title":{"rendered":"Jambon au thon assaisonn\u00e9"},"content":{"rendered":"<div>\n<h1>Jambon au thon assaisonn\u00e9<\/h1>\n<p>Le jambon au thon est obtenu \u00e0 partir d\u2019un filet de thon \u00e0 nageoires jaunes m\u00e9diterran\u00e9ennes, sal\u00e9 avec du sel Volterra et laiss\u00e9 s\u00e9cher lentement au soleil, apr\u00e8s quoi il est vieilli dans l\u2019obscurit\u00e9 pendant 12 mois. Comme le jambon de porc, il doit \u00eatre d\u00e9gust\u00e9 tr\u00e8s fin. Servez-le sur une bruschetta assaisonn\u00e9e d\u2019huile d\u2019olive extra vierge et de citron, ou accompagn\u00e9 de tomates m\u00fbres. Il peut \u00eatre coup\u00e9 en tranches tr\u00e8s fines \u00e0 servir directement sur un plateau de \u00ab Salumi di Mare \u00bb assaisonn\u00e9 \u00e0 l\u2019huile d\u2019olive extra vierge ou accompagn\u00e9 d\u2019une burrata apulie ou d\u2019un fromage frais tendre. Excellent comme carpaccio dans une entr\u00e9e raffin\u00e9e avec d\u2019autres produits de notre gamme, ou comme d\u2019autres recettes imaginatives que le chef juge appropri\u00e9es \u00e0 d\u00e9velopper. Unique en son genre pour la forte quantit\u00e9 de prot\u00e9ines (environ 35 %) et un faible apport calorique, le jambon au thon pr\u00e9sente d\u2019autres caract\u00e9ristiques, notamment une r\u00e9duction de la teneur en mati\u00e8res grasses (seulement 0,8 %), des min\u00e9raux comme le s\u00e9l\u00e9nium, le potassium et le phosphore ; ainsi que des om\u00e9ga 3 et 6. \u00c9tant \u00e9galement sans gluten, il peut \u00eatre utilis\u00e9 sans restriction dans l\u2019alimentation des c\u0153liaques. C\u2019est un produit gastronomique tr\u00e8s pr\u00e9cieux, obtenu \u00e0 partir de la pr\u00e9paration du filet maigre de thon jaune. Assaisonn\u00e9 avec une ventilation naturelle, il poss\u00e8de une saveur intense ; il doit \u00eatre coup\u00e9 en fines tranches assaisonn\u00e9es d\u2019huile d\u2019olive extra vierge et quelques gouttes de citron. Il est \u00e9galement consomm\u00e9 en combinaison avec des salades.<\/p>\n<\/div>\n<div>\n<ul>\n<li>Teneur \u00e9lev\u00e9e en prot\u00e9ines Environ 36 %<\/li>\n<li>Matur\u00e9 sur 10 mois<\/li>\n<li>R\u00e9duction de la teneur en mati\u00e8res grasses (seulement 0,9 %)<\/li>\n<li>Il contient des Om\u00e9ga 3 et 6, pr\u00e9cieux alli\u00e9s de notre corps<\/li>\n<li>Elle contient de nombreux min\u00e9raux tels que le potassium, le s\u00e9l\u00e9nium et le phosphore<\/li>\n<li>Il existe aussi des vitamines B<\/li>\n<li>Id\u00e9al dans les r\u00e9gimes pauvres en calories<\/li>\n<li>Sans gluten<\/li>\n<li>Incroyablement bon et l\u00e9ger, id\u00e9al pour les r\u00e9gimes pauvres en calories.<\/li>\n<li>Adapt\u00e9 aux sportifs et aux passionn\u00e9s de sant\u00e9<\/li>\n<\/ul>\n<h3>Jambon au thon assaisonn\u00e9<\/h3>\n<p><strong>Maturation : plus de 10 MOIS<br \/>\n<\/strong> <strong>Emballage : <\/strong>emballage sous vide<br \/>\n<strong>Poids net : 500 grains<br \/>\n<\/strong> <strong>Dur\u00e9e de conservation : 6<\/strong>jours<br \/>\n<strong>Disponibilit\u00e9 : <\/strong>toute l\u2019ann\u00e9e<\/p>\n<ul>\n<li>Prix \u20ac\/kg 106\n<p>Ingr\u00e9dients : <strong>THON jaune<\/strong> (Thunnus albacares), \u00e9pices, sel Volterra, sucre de canne.<\/li>\n<\/ul>\n<p>ALLERG\u00c8NES :<strong> POISSON<br \/>\n<\/strong>: Peut contenir des traces de :<strong> MOLLUSQUES, NOIX, CRUSTAC\u00c9S<\/strong><\/p>\n<\/div>\n<div>\n<div class=\"mceTemp\">\n<div class=\"tabella-nutrizionale-container\" style=\"max-width: 400px; margin: 20px 0; font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Helvetica, Arial, sans-serif; border: 1px solid #e0e0e0; border-radius: 8px; overflow: hidden; box-shadow: 0 2px 4px rgba(0,0,0,0.05);\">\n<div style=\"background-color: #f8f9fa; padding: 15px; border-bottom: 2px solid #222;\">\n<h3 style=\"margin: 0; font-size: 18px; font-weight: bold; uppercase; color: #222;\">Valeurs nutritionnelles<\/h3>\n<p style=\"margin: 5px 0 0 0; font-size: 13px; color: #666; font-style: italic;\">Valeurs moyennes pour 100g de produit<\/p>\n<\/div>\n<table style=\"width: 100%; border-collapse: collapse; margin: 0; background: #fff;\">\n<tbody>\n<tr style=\"border-bottom: 1px solid #eeeeee;\">\nValeur <\/p>\n<td style=\"padding: 12px 15px; font-weight: 600; color: #222; font-size: 14px;\">\u00e9nerg\u00e9tique<\/td>\n<td style=\"padding: 12px 15px; text-align: right; font-weight: 600; color: #222; font-size: 14px;\">636 kJ \/ 152 kcal<\/td>\n<\/tr>\n<tr style=\"border-bottom: 1px solid #eeeeee;\">\n<td style=\"padding: 12px 15px; font-weight: 600; color: #222; font-size: 14px;\">Gras<\/td>\n<td style=\"padding: 12px 15px; text-align: right; color: #333; font-size: 14px;\">0,8 g<\/td>\n<\/tr>\n<tr style=\"border-bottom: 1px solid #eeeeee; background-color: #fafafa;\">\n<td style=\"padding: 10px 15px 10px 30px; color: #666; font-size: 13px;\"><em>dont Acides gras satur\u00e9s<\/em><\/td>\n<td style=\"padding: 10px 15px; text-align: right; color: #666; font-size: 13px;\">0,1 g<\/td>\n<\/tr>\n<tr style=\"border-bottom: 1px solid #eeeeee;\">\n<td style=\"padding: 12px 15px; font-weight: 600; color: #222; font-size: 14px;\">Glucides<\/td>\n<td style=\"padding: 12px 15px; text-align: right; color: #333; font-size: 14px;\">1,2 g<\/td>\n<\/tr>\n<tr style=\"border-bottom: 1px solid #eeeeee; background-color: #fafafa;\">\n<td style=\"padding: 10px 15px 10px 30px; color: #666; font-size: 13px;\"><em>dont Sucres<\/em><\/td>\n<td style=\"padding: 10px 15px; text-align: right; color: #666; font-size: 13px;\">0,8 g<\/td>\n<\/tr>\n<tr style=\"border-bottom: 1px solid #eeeeee;\">\n<td style=\"padding: 12px 15px; font-weight: 600; color: #222; font-size: 14px;\">Prot\u00e9ine<\/td>\n<td style=\"padding: 12px 15px; text-align: right; color: #333; font-size: 14px;\">35 g<\/td>\n<\/tr>\n<tr style=\"border-bottom: 1px solid #222;\">\n<td style=\"padding: 12px 15px; font-weight: 600; color: #222; font-size: 14px;\">Sel<\/td>\n<td style=\"padding: 12px 15px; text-align: right; color: #333; font-size: 14px;\">0,8 g<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Excellent en entr\u00e9e avec un filet d\u2019huile d\u2019olive extra vierge et un peu de jus de citron Sorrento, comme plat complet avec un accompagnement de l\u00e9gumes cuits et vapeur ou grill\u00e9s, ou encore en petit pain farci \u00e0 la burrata Pugliese.<br \/>\n Prix \u20ac\/kg 105,92<\/p>\n","protected":false},"featured_media":22148,"comment_status":"open","ping_status":"closed","template":"","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","om_disable_all_campaigns":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"slim_seo":{"title":"Jambon au thon assaisonn\u00e9","description":"Le Prosciutto di Tonno Salumeria Ittica est un produit gastronomique tr\u00e8s raffin\u00e9, obtenu \u00e0 partir de la pr\u00e9paration du filet maigre de thon jaune de la M\u00e9diterran\u00e9e et assaisonn\u00e9 avec une ventilation naturelle."}},"product_brand":[],"product_cat":[3768,1634],"product_tag":[3770,3772,3771,3773,3499,3769],"class_list":["post-22129","product","type-product","status-publish","has-post-thumbnail","product_cat-tuna-bresaola","product_cat-viandes-sechees","product_tag-jambon","product_tag-jambon-au-poisson","product_tag-jambon-au-thon","product_tag-poisson-sale","product_tag-thon","product_tag-thon-seche","first","instock","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/salumeriaittica.org\/fr\/wp-json\/wp\/v2\/product\/22129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salumeriaittica.org\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/salumeriaittica.org\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/salumeriaittica.org\/fr\/wp-json\/wp\/v2\/comments?post=22129"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/salumeriaittica.org\/fr\/wp-json\/wp\/v2\/media\/22148"}],"wp:attachment":[{"href":"https:\/\/salumeriaittica.org\/fr\/wp-json\/wp\/v2\/media?parent=22129"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/salumeriaittica.org\/fr\/wp-json\/wp\/v2\/product_brand?post=22129"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/salumeriaittica.org\/fr\/wp-json\/wp\/v2\/product_cat?post=22129"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/salumeriaittica.org\/fr\/wp-json\/wp\/v2\/product_tag?post=22129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}