{"id":21653,"date":"2021-11-29T15:51:33","date_gmt":"2021-11-29T15:51:33","guid":{"rendered":"https:\/\/salumeriaittica.org\/prodotto\/thon-fume\/"},"modified":"2026-08-31T15:54:52","modified_gmt":"2026-08-31T15:54:52","slug":"thon-fume","status":"publish","type":"product","link":"https:\/\/salumeriaittica.org\/fr\/prodotto\/thon-fume\/","title":{"rendered":"Thon fum\u00e9"},"content":{"rendered":"<div>\n<h4>Thon fum\u00e9<\/h4>\n<p>Ingr\u00e9dients : thon jaune, sel, dextrose, ar\u00f4mes naturels, \u00e9pices<br \/>\nFum\u00e9 naturellement avec du bois de h\u00eatre<\/p>\n<\/div>\n<div>\n<div class=\"mceTemp\"><\/div>\n<p>Le thon fum\u00e9 est trait\u00e9 avec un grand soin dans tous les processus de production : de la p\u00eache au fumage, cette entreprise propose des produits haut de gamme gr\u00e2ce \u00e0 des contr\u00f4les de qualit\u00e9 continus et complets \u00e0 toutes les \u00e9tapes.<br \/>\n Un produit parfait : une tranche de thon jaune, nettoy\u00e9e, barbel\u00e9e et fum\u00e9e avec du bois de h\u00eatre.<br \/>\n Un produit id\u00e9al pour les entr\u00e9es ou les plats principaux l\u00e9gers de fruits de mer, \u00e0 accompagner directement par exemple d\u2019une salade m\u00e9lang\u00e9e.<\/p>\n<p>L\u2019entreprise<br \/>\nCette entreprise danoise est une marque historique de viandes de poisson, d\u00e9sormais consolid\u00e9e sur le march\u00e9 italien de la restauration et \u00e0 l\u2019\u00e9tranger.<br \/>\n Gr\u00e2ce \u00e0 notre processus de s\u00e9lection minutieux des mati\u00e8res premi\u00e8res et \u00e0 la confiance que nous accordons \u00e0 nos partenaires et \u00e0 leur exp\u00e9rience, nous proposons des sp\u00e9cialit\u00e9s de poisson apparemment simples, mais difficiles \u00e0 pr\u00e9parer.<br \/>\n Produits de la mer, l\u00e9g\u00e8rement transform\u00e9s avec comp\u00e9tence par nos producteurs historiques : tr\u00e8s peu d\u2019ingr\u00e9dients, mais un processus de s\u00e9chage exclusif qui fait la diff\u00e9rence pour pr\u00e9server la fra\u00eecheur du poisson.<\/p>\n<p>Emballage<br \/>\n sous vide<\/p>\n<p>\u00c9tiquette du produit : les informations fournies sur les produits peuvent varier en raison de modifications apport\u00e9es par les fabricants, ce qui pourrait temporairement provoquer des variations entre les informations du site et celles affich\u00e9es sur les produits livr\u00e9s.<br \/>\n Nous vous invitons donc \u00e0 v\u00e9rifier les informations sur l\u2019\u00e9tiquette ou l\u2019emballage du produit avant de le consommer ou de l\u2019utiliser.<br \/>\n Pour plus d\u2019informations concernant les caract\u00e9ristiques techniques du produit, veuillez contacter notre service client<\/p>\n<p>Origine : Danemark<\/p>\n<p>Pr\u00e9cision du poids indiqu\u00e9 : le poids indiqu\u00e9 peut \u00eatre l\u00e9g\u00e8rement d\u00e9cal\u00e9 en raison de la d\u00e9coupe de la pi\u00e8ce ou du type de produit.<\/p>\n<p>ALLERG\u00c8NES :<strong> POISSON<br \/>\n<\/strong>: Peut contenir des traces de :<strong> MOLLUSQUES, NOIX, CRUSTAC\u00c9S<\/strong><\/p>\n<ul>\n<li><strong data-start=\"1459\" data-end=\"1472\">Prix \u20ac\/kg 53,54<\/strong><\/li>\n<\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le thon fum\u00e9 est trait\u00e9 avec un grand soin dans tous les processus de production : de la p\u00eache au fumage, cette entreprise propose des produits haut de gamme gr\u00e2ce \u00e0 des contr\u00f4les de qualit\u00e9 continus et complets \u00e0 toutes les \u00e9tapes.<br \/>\n Un produit parfait : une tranche de thon jaune, nettoy\u00e9e, barbel\u00e9e et fum\u00e9e avec du h\u00eatre.<br \/>\n Prix \u20ac\/kg 53,54<\/p>\n","protected":false},"featured_media":21968,"comment_status":"open","ping_status":"closed","template":"","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","om_disable_all_campaigns":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"slim_seo":{"title":"Tuna Bresaola - \u00ab Salumi di Mare \u00bb de Salumeria Ittica","description":"Le thon Bresaola Salumeria Ittica est un produit gastronomique tr\u00e8s raffin\u00e9, obtenu \u00e0 partir de la pr\u00e9paration du filet maigre de thon jaune m\u00e9diterran\u00e9en et assaisonn\u00e9 avec une ventilation naturelle, il est trait\u00e9 directement dans notre usine de production en Toscane."}},"product_brand":[],"product_cat":[3489,1428,1392,1397],"product_tag":[3501,3499,3500],"class_list":["post-21653","product","type-product","status-publish","has-post-thumbnail","product_cat-carpaccio","product_cat-fume","product_cat-sans-gluten","product_cat-sans-lactose","product_tag-carpaccio-de-thon","product_tag-thon","product_tag-thon-fume","yith_product_brand-epicerie-de-poisson","first","instock","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/salumeriaittica.org\/fr\/wp-json\/wp\/v2\/product\/21653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salumeriaittica.org\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/salumeriaittica.org\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/salumeriaittica.org\/fr\/wp-json\/wp\/v2\/comments?post=21653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/salumeriaittica.org\/fr\/wp-json\/wp\/v2\/media\/21968"}],"wp:attachment":[{"href":"https:\/\/salumeriaittica.org\/fr\/wp-json\/wp\/v2\/media?parent=21653"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/salumeriaittica.org\/fr\/wp-json\/wp\/v2\/product_brand?post=21653"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/salumeriaittica.org\/fr\/wp-json\/wp\/v2\/product_cat?post=21653"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/salumeriaittica.org\/fr\/wp-json\/wp\/v2\/product_tag?post=21653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}