{"id":22618,"date":"2017-10-04T11:54:06","date_gmt":"2017-10-04T11:54:06","guid":{"rendered":"https:\/\/salumeriaittica.org\/prodotto\/cuore-di-tonno-rosso\/"},"modified":"2026-08-31T16:49:12","modified_gmt":"2026-08-31T16:49:12","slug":"cuore-di-tonno-rosso","status":"publish","type":"product","link":"https:\/\/salumeriaittica.org\/es\/prodotto\/cuore-di-tonno-rosso\/","title":{"rendered":"Coraz\u00f3n de at\u00fan rojo"},"content":{"rendered":"<h1>Coraz\u00f3n de at\u00fan rojo<\/h1>\n<p>AT\u00daN ROJO CORAZ\u00d3N DE SICILIA<\/p>\n<h2>El coraz\u00f3n<\/h2>\n<p>Es el primer producto del procesamiento de entra\u00f1as de at\u00fan. El procedimiento es muy similar al de la bottarga: se sale y se tritura en dos pesos y luego se deja secar tras 20 d\u00edas. <\/p>\n<p>La producci\u00f3n es artesanal seg\u00fan la antigua receta de la pesquer\u00eda de at\u00fan de Trapani.<br \/>\n El formato de peso debe elegirse en el men\u00fa desplegable.<br \/>\n El peso del producto, al ser artesanal y artesanal, puede variar unos pocos gramos.<\/p>\n<ul>\n<li>Precio \u20ac\/kg 101,12<\/li>\n<\/ul>\n<p>AL\u00c9RGENOS:<strong> PESCADO<br \/>\n<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El coraz\u00f3n del at\u00fan Es el primer producto del procesamiento de entra\u00f1as de at\u00fan. El procedimiento es muy similar al de la bottarga: salada y triturada en dos pesos y luego dejada secar tras 20 d\u00edas. La producci\u00f3n es artesanal seg\u00fan la antigua receta de la pesca de at\u00fan de Trapani.<br \/>\n Precio \u20ac\/kg 110,00  <\/p>\n","protected":false},"featured_media":22621,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","om_disable_all_campaigns":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"slim_seo":{"title":"Coraz\u00f3n del at\u00fan rojo siciliano - \"Salumi di Mare\" de Salumeria Ittica","description":"El coraz\u00f3n del at\u00fan Es el primer producto del procesamiento de entra\u00f1as de at\u00fan. El procedimiento es muy similar al de la bottarga: salada y triturada con dos pesos y luego dejada secar tras 20 d\u00edas. La producci\u00f3n es artesanal seg\u00fan la antigua receta de la pesca de at\u00fan de Trapani."}},"product_brand":[],"product_cat":[3152,1988],"product_tag":[3154,3155,4092,4093,1992,2023,3153,3156,2026],"class_list":["post-22618","product","type-product","status-publish","has-post-thumbnail","product_cat-bottarghe","product_cat-embutidos-curados","product_tag-bottarga","product_tag-bottarga-de-atun","product_tag-cuore","product_tag-cuore-di-tonno","product_tag-delicatessen-de-pescado","product_tag-embutidos-curados-de-marisco","product_tag-productos-ecologicos","product_tag-sicilia","product_tag-sin-gluten","yith_product_brand-embutidos-curados-de-marisco","first","instock","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"_links":{"self":[{"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/product\/22618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/comments?post=22618"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/media\/22621"}],"wp:attachment":[{"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/media?parent=22618"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/product_brand?post=22618"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/product_cat?post=22618"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/product_tag?post=22618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}