{"id":22342,"date":"2019-11-03T09:33:56","date_gmt":"2019-11-03T09:33:56","guid":{"rendered":"https:\/\/salumeriaittica.org\/prodotto\/crema-de-salmon-200g\/"},"modified":"2019-11-03T09:33:56","modified_gmt":"2019-11-03T09:33:56","slug":"crema-de-salmon-200g","status":"publish","type":"product","link":"https:\/\/salumeriaittica.org\/es\/prodotto\/crema-de-salmon-200g\/","title":{"rendered":"Crema de salm\u00f3n 200g"},"content":{"rendered":"<div>\n<h3 data-start=\"238\" data-end=\"330\">\ud83d\udc1f <strong data-start=\"245\" data-end=\"330\">Crema de Salm\u00f3n Ahumado 200g \u2013 Sabor refinado y vers\u00e1til para cualquier ocasi\u00f3n<\/strong><\/h3>\n<p data-start=\"332\" data-end=\"623\"><strong data-start=\"335\" data-end=\"373\">La Crema de Salm\u00f3n Ahumado Baltik<\/strong> es una especialidad gourmet elaborada con <strong data-start=\"414\" data-end=\"450\">salm\u00f3n delicadamente ahumado<\/strong> y elaborada a mano para realzar el sabor y la textura. Ideal para quienes quieren aportar un condimento fino y listo para usar con calidad profesional. <\/p>\n<p data-start=\"625\" data-end=\"861\">Perfecto para <strong data-start=\"638\" data-end=\"662\">condimentar los primeros platos<\/strong> como \u00f1oquis de patata, linguini o paccheri, pero tambi\u00e9n irresistiblemente untados en <strong data-start=\"743\" data-end=\"771\">crutones de pan blandos<\/strong>, canap\u00e9s o bruschetta para enriquecer buffets y aperitivos con un toque elegante y sabroso.<\/p>\n<p data-start=\"863\" data-end=\"1081\">Elaborada con <strong data-start=\"878\" data-end=\"897\">verduras frescas<\/strong>, sin gluten y <strong data-start=\"916\" data-end=\"949\">sin conservantes artificiales<\/strong>, esta crema est\u00e1 dise\u00f1ada para satisfacer las necesidades del consumidor preocupado por la calidad, tanto en casa como profesionalmente.<\/p>\n<p data-start=\"1083\" data-end=\"1375\">Rica en <strong data-start=\"1092\" data-end=\"1113\">omega 3 y omega 6<\/strong>, tambi\u00e9n es una fuente natural de <strong data-start=\"1145\" data-end=\"1168\">minerales esenciales<\/strong> (calcio, yodo, f\u00f3sforo, potasio, zinc, selenio) y <strong data-start=\"1222\" data-end=\"1240\">vitaminas A y B<\/strong>, manteniendo un <strong data-start=\"1256\" data-end=\"1303\">bajo contenido cal\u00f3rico y grasas saturadas<\/strong>. Una excelente opci\u00f3n para quienes siguen una dieta saludable y refinada. <\/p>\n<hr data-start=\"1377\" data-end=\"1380\">\n<h3 data-start=\"1382\" data-end=\"1419\">\u2705 <strong data-start=\"1388\" data-end=\"1419\">Caracter\u00edsticas principales:<\/strong><\/h3>\n<ul data-start=\"1420\" data-end=\"1604\">\n<li data-start=\"1420\" data-end=\"1439\">\n<p data-start=\"1422\" data-end=\"1439\"><strong data-start=\"1422\" data-end=\"1433\">Tama\u00f1o<\/strong>: 200g<\/p>\n<\/li>\n<li data-start=\"1440\" data-end=\"1459\">\n<p data-start=\"1442\" data-end=\"1459\"><strong data-start=\"1442\" data-end=\"1459\">Sin gluten<\/strong><\/p>\n<\/li>\n<li data-start=\"1460\" data-end=\"1523\">\n<p data-start=\"1462\" data-end=\"1523\"><strong data-start=\"1462\" data-end=\"1480\">Instrucciones de uso<\/strong>: pasta, picatostes, bruschetta, aperitivos<\/p>\n<\/li>\n<li data-start=\"1524\" data-end=\"1574\">\n<p data-start=\"1526\" data-end=\"1574\"><strong data-start=\"1526\" data-end=\"1574\">Hecho a mano con ingredientes frescos<\/strong><\/p>\n<\/li>\n<li data-start=\"1575\" data-end=\"1604\">\n<p data-start=\"1577\" data-end=\"1604\"><strong data-start=\"1577\" data-end=\"1590\">Al\u00e9rgenos<\/strong>: PESCADO, LECHE<\/p>\n<ul>\n<li>Precio \u20ac\/kg 27,50<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/div>\n<div>\n<p><a href=\"https:\/\/salumeriaittica.org\/es\/categoria-prodotto\/ragout-y-salsas\/\">Crema de salm\u00f3n 200g<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Crema de salm\u00f3n 200g excelente para sazonar pasta (sensacional en \u00f1oquis de patata) o untada sobre crutones blandos de pan para enriquecer los buffets y satisfacer el paladar.<br \/>\n A las caracter\u00edsticas \u00fanicas del procesamiento tradicional realizado escrupulosamente a mano tambi\u00e9n se a\u00f1ade el envasado.<br \/>\n Precio \u20ac\/kg 27,50<\/p>\n","protected":false},"featured_media":21076,"comment_status":"open","ping_status":"closed","template":"","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","om_disable_all_campaigns":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"slim_seo":{"title":"Crema de salm\u00f3n 200g","description":"Descubre la Baltik Smoked Salmon Cream de 200g, ideal para platos de pasta y canap\u00e9s. Sin gluten, artesanal, con omega 3 e ingredientes frescos."}},"product_brand":[],"product_cat":[2022,1518,2033,1360],"product_tag":[1419,2376,2047,2072,2115,2048,1418,2116,2046,2049,2053,2377,2052,2024,2051,2026],"class_list":["post-22342","product","type-product","status-publish","has-post-thumbnail","product_cat-ragout-y-salsas","product_cat-reserva","product_cat-reservas","product_cat-sin-gluten","product_tag-cestas-navidenas","product_tag-crema-di-scampi","product_tag-ideas-de-regalos-de-navidad","product_tag-regalos-de-navidad-3","product_tag-regalos-de-navidad-4","product_tag-regalos-de-navidad-2","product_tag-regalos-de-navidad","product_tag-regalos-de-navidad-en-amazon","product_tag-regalos-de-navidad-para-empresas","product_tag-regalos-originales-de-navidad","product_tag-reservas","product_tag-ricetta-penne-alla-crema-di-scampi","product_tag-salsa-2","product_tag-salsa-de-carne","product_tag-salsas","product_tag-sin-gluten","yith_product_brand-salsas-de-marisco","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/product\/22342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/comments?post=22342"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/media\/21076"}],"wp:attachment":[{"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/media?parent=22342"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/product_brand?post=22342"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/product_cat?post=22342"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/product_tag?post=22342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}