{"id":22217,"date":"2020-04-11T15:38:47","date_gmt":"2020-04-11T15:38:47","guid":{"rendered":"https:\/\/salumeriaittica.org\/prodotto\/soppressata-di-scoglio\/"},"modified":"2026-08-31T15:55:40","modified_gmt":"2026-08-31T15:55:40","slug":"soppressata-di-scoglio","status":"publish","type":"product","link":"https:\/\/salumeriaittica.org\/es\/prodotto\/soppressata-di-scoglio\/","title":{"rendered":"Soppressata di Scoglio"},"content":{"rendered":"<div>\n<h1>Soppressata di Scoglio<\/h1>\n<p>Las soppressata de pescado elaboradas con moluscos y crust\u00e1ceos cocidos, gambas, sepias y calamares se aromatizan con plantas arom\u00e1ticas y especias.<br \/>\nLa rodaja es firme y compacta. El color naranja de las gambas alterna con el blanco de la sepia y el violeta del pulpo.<br \/>\n El sabor es dulce, t\u00edpico de moluscos y crust\u00e1ceos, ideal para carpaccio original de pescado acompa\u00f1ado de verduras frescas o cocidas.<br \/>\n Tambi\u00e9n sabroso cortado en cubos, ideal para hacer carpaccio muy fino y variedad de colores para ensaladas verdes. <\/p>\n<\/div>\n<div>\n<ul>\n<li>Alto contenido proteico Aprox. 32%<\/li>\n<li>Contenido reducido de grasa (solo 1,2%)<\/li>\n<li>Contiene Omega 3 y 6, aliados preciosos de nuestro cuerpo<\/li>\n<li>Contiene muchos minerales como potasio, selenio y f\u00f3sforo<\/li>\n<li>Tambi\u00e9n hay vitaminas del grupo B<\/li>\n<li>Ideal en dietas bajas en calor\u00edas<\/li>\n<li>Sin gluten<\/li>\n<li>Sin lactosa<\/li>\n<li>Incre\u00edblemente bueno y ligero, ideal para dietas bajas en calor\u00edas.<\/li>\n<li>Adecuado para deportistas y entusiastas de la salud<\/li>\n<\/ul>\n<\/div>\n<div>\n<p>y que mantiene toda la ligereza t\u00edpica del pescado crudo pero con la m\u00e1xima garant\u00eda de alimento.<\/p>\n<h1>Soppressata di Scoglio<br \/>\n<a href=\"https:\/\/salumeriaittica.org\/es\/categoria-prodotto\/carpaccio\/\">https:\/\/salumeriaittica.org\/categoria-prodotto\/carpacci\/<\/a><\/h1>\n<p><strong>Embalaje: <\/strong>envase al vac\u00edo<\/p>\n<p><strong>Peso: Elige entre los pesos disponibles<\/strong><\/p>\n<p><strong>Duraci\u00f3n: <\/strong>50 d\u00edas<\/p>\n<p><strong>Disponibilidad: <\/strong>todo el a\u00f1o<\/p>\n<ul>\n<li>Precio \u20ac\/kg 70,22Ingredientes: <strong>PULPO COCIDO<\/strong> 25%, <strong>SEPIA<\/strong> cocida 25%, <strong>mejillones cocidos<\/strong> 20%, <strong>ALMEJAS cocidas<\/strong> 20%, <strong>GELATINA de PESCADO<\/strong>, ajo, pimienta, sal Volterra, az\u00facar.<\/li>\n<\/ul>\n<p>AL\u00c9RGENOS:<strong> MOLUSCOS:<br \/>\n<\/strong>Puede contener trazas de:<strong> PESCADO, FRUTOS SECOS, CRUST\u00c1CEOS<\/strong><\/p>\n<div class=\"tabella-nutrizionale-container\" style=\"max-width: 400px; margin: 20px 0; font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Helvetica, Arial, sans-serif; border: 1px solid #e0e0e0; border-radius: 8px; overflow: hidden; box-shadow: 0 2px 4px rgba(0,0,0,0.05);\">\n<div style=\"background-color: #f8f9fa; padding: 15px; border-bottom: 2px solid #222;\">\n<h3 style=\"margin: 0; font-size: 18px; font-weight: bold; uppercase; color: #222;\">Valores nutricionales<\/h3>\n<p style=\"margin: 5px 0 0 0; font-size: 13px; color: #666; font-style: italic;\">Valores medios por cada 100g de producto<\/p>\n<\/div>\n<table style=\"width: 100%; border-collapse: collapse; margin: 0; background: #fff;\">\n<tbody>\n<tr style=\"border-bottom: 1px solid #eeeeee;\">\nValor <\/p>\n<td style=\"padding: 12px 15px; font-weight: 600; color: #222; font-size: 14px;\">energ\u00e9tico<\/td>\n<td style=\"padding: 12px 15px; text-align: right; font-weight: 600; color: #222; font-size: 14px;\">636 kJ \/ 152 kcal<\/td>\n<\/tr>\n<tr style=\"border-bottom: 1px solid #eeeeee;\">\n<td style=\"padding: 12px 15px; font-weight: 600; color: #222; font-size: 14px;\">Grasa<\/td>\n<td style=\"padding: 12px 15px; text-align: right; color: #333; font-size: 14px;\">0,8 g<\/td>\n<\/tr>\n<tr style=\"border-bottom: 1px solid #eeeeee; background-color: #fafafa;\">\n<td style=\"padding: 10px 15px 10px 30px; color: #666; font-size: 13px;\"><em>de los cuales \u00e1cidos grasos saturados<\/em><\/td>\n<td style=\"padding: 10px 15px; text-align: right; color: #666; font-size: 13px;\">0,1 g<\/td>\n<\/tr>\n<tr style=\"border-bottom: 1px solid #eeeeee;\">\n<td style=\"padding: 12px 15px; font-weight: 600; color: #222; font-size: 14px;\">Carbohidratos<\/td>\n<td style=\"padding: 12px 15px; text-align: right; color: #333; font-size: 14px;\">1,2 g<\/td>\n<\/tr>\n<tr style=\"border-bottom: 1px solid #eeeeee; background-color: #fafafa;\">\n<td style=\"padding: 10px 15px 10px 30px; color: #666; font-size: 13px;\"><em>de los cuales az\u00facares<\/em><\/td>\n<td style=\"padding: 10px 15px; text-align: right; color: #666; font-size: 13px;\">0,5 g<\/td>\n<\/tr>\n<tr style=\"border-bottom: 1px solid #eeeeee;\">\n<td style=\"padding: 12px 15px; font-weight: 600; color: #222; font-size: 14px;\">Prote\u00edna<\/td>\n<td style=\"padding: 12px 15px; text-align: right; color: #333; font-size: 14px;\">35 g<\/td>\n<\/tr>\n<tr style=\"border-bottom: 1px solid #222;\">\n<td style=\"padding: 12px 15px; font-weight: 600; color: #222; font-size: 14px;\">Sal<\/td>\n<td style=\"padding: 12px 15px; text-align: right; color: #333; font-size: 14px;\">0,8 g<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<h2>El sabor y aroma <a href=\"https:\/\/salumidimare.com\/prodotti\/salami-insaccati\/carpaccio-di-scoglio-mediterraneo\/\">de Soppressata di Scoglio<\/a><\/h2>\n<p>C\u00f3rtalo finamente con un cuchillo o, mejor a\u00fan, con un cortador, como si fuera un salami y ponlo en un plato de servir con ensalada, o puedes hacer panecillos rellenos de pur\u00e9 de patatas con perejil. Tambi\u00e9n es excelente en un plato como carne en rodajas sazonada con aceite de oliva virgen extra. <\/p>\n<div class=\"mceTemp\"><\/div>\n<p>&nbsp;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Las soppressatas de pescado elaboradas con moluscos y crust\u00e1ceos cocidos, gambas, sepias y calamares se aromatizan con plantas arom\u00e1ticas y especias.<br \/>\n La rodaja es firme y compacta. El color naranja de las gambas alterna con el blanco de la sepia y la violeta del pulpo.<br \/>\n El sabor es dulce, t\u00edpico de moluscos y crust\u00e1ceos, ideal para carpaccio original de pescado acompa\u00f1ado de verduras frescas o cocidas.<br \/>\n Tambi\u00e9n sabroso cortado en cubos, ideal para hacer carpaccios muy finos y variedad de colores para ensaladas verdes.<br \/>\n Precio \u20ac\/kg 70,22 <\/p>\n","protected":false},"featured_media":22219,"comment_status":"open","ping_status":"closed","template":"","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","om_disable_all_campaigns":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"slim_seo":{"title":"Salami de roca Soppressata Carpaccio - \"Salumi di Mare\"","description":"La soppressata de pescado hecha con moluscos y crust\u00e1ceos cocidos, gambas, sepias y calamares se aromatiza con plantas arom\u00e1ticas y especias. La rodaja es firme y compacta. El color naranja de las gambas alterna con el blanco de la sepia y el violeta del pulpo."}},"product_brand":[],"product_cat":[2895,3440,1360,1363],"product_tag":[3835,3837,1992,2751,2754,3838,3833,2026,2050,3836,3834],"class_list":["post-22217","product","type-product","status-publish","has-post-thumbnail","product_cat-carpaccio","product_cat-embutidos-curados-2","product_cat-sin-gluten","product_cat-sin-lactosa","product_tag-carpaccio","product_tag-carpaccio-de-roca","product_tag-delicatessen-de-pescado","product_tag-productos-sin-gluten","product_tag-productos-sin-lactosa","product_tag-rock","product_tag-salami-de-pulpo","product_tag-sin-gluten","product_tag-sin-lactosa","product_tag-soppressata-di-scoglio","product_tag-suppressata","yith_product_brand-embutidos-curados-de-marisco","first","instock","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/product\/22217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/comments?post=22217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/media\/22219"}],"wp:attachment":[{"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/media?parent=22217"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/product_brand?post=22217"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/product_cat?post=22217"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/product_tag?post=22217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}