{"id":21245,"date":"2019-10-05T08:41:39","date_gmt":"2019-10-05T08:41:39","guid":{"rendered":"https:\/\/salumeriaittica.org\/prodotto\/crema-di-scampi-200g-spalmabile-gourmet-per-pasta-e-crostini\/"},"modified":"2026-08-31T16:50:39","modified_gmt":"2026-08-31T16:50:39","slug":"crema-di-scampi-200g-spalmabile-gourmet-per-pasta-e-crostini","status":"publish","type":"product","link":"https:\/\/salumeriaittica.org\/es\/prodotto\/crema-di-scampi-200g-spalmabile-gourmet-per-pasta-e-crostini\/","title":{"rendered":"Scampi Cream 200g"},"content":{"rendered":"<h3 data-start=\"188\" data-end=\"285\">\ud83d\udc1a <strong data-start=\"195\" data-end=\"285\">Scampi Cream 200g \u2013 Sabor aut\u00e9ntico del mar, ideal para primeros platos y aperitivos<\/strong><\/h3>\n<p data-start=\"287\" data-end=\"666\">Descubre el inconfundible sabor <strong data-start=\"324\" data-end=\"350\">de la Scampi Cream<\/strong>, una especialidad lista para usar dise\u00f1ada para realzar tus platos de marisco. Elaborada con <strong data-start=\"441\" data-end=\"478\">ingredientes frescos y seleccionados<\/strong>, es perfecta para condimentar platos refinados \u2013 como \u00f1oquis de patata o linguini \u2013 o para servirse sobre <strong data-start=\"592\" data-end=\"619\">picatostes de pan blanco<\/strong> en un aperitivo o buffet con un sabor refinado. <\/p>\n<p data-start=\"668\" data-end=\"958\">Esta crema, elaborada a <strong data-start=\"691\" data-end=\"717\">mano<\/strong>, garantiza la m\u00e1xima calidad y frescura, gracias a las verduras frescas y a un procesamiento que respeta la tradici\u00f3n culinaria italiana. Tambi\u00e9n ideal para restauradores y amantes de la cocina que buscan un producto gourmet sin concesiones. <\/p>\n<p data-start=\"960\" data-end=\"1271\">Naturalmente enriquecida con <strong data-start=\"988\" data-end=\"1009\">Omega 3 y Omega 6<\/strong>, la crema de scampi es un alimento <strong data-start=\"1044\" data-end=\"1074\">bajo en calor\u00edas<\/strong>, rico en prote\u00ednas, calcio, yodo, f\u00f3sforo, potasio, zinc y vitaminas A y B. Un aliado ideal en <strong data-start=\"1174\" data-end=\"1194\">dietas equilibradas<\/strong>, tanto para deportistas como para quienes quieren variar su dieta seg\u00fan el sabor.<\/p>\n<hr data-start=\"1273\" data-end=\"1276\">\n<h3 data-start=\"1278\" data-end=\"1304\">\u2705 <strong data-start=\"1284\" data-end=\"1304\">Caracter\u00edsticas:<\/strong><\/h3>\n<ul data-start=\"1305\" data-end=\"1551\">\n<li data-start=\"1305\" data-end=\"1335\">\n<p data-start=\"1307\" data-end=\"1335\"><strong data-start=\"1307\" data-end=\"1318\">Formato<\/strong>: tarro de 200g<\/p>\n<\/li>\n<li data-start=\"1336\" data-end=\"1355\">\n<p data-start=\"1338\" data-end=\"1355\"><strong data-start=\"1338\" data-end=\"1355\">Sin gluten<\/strong><\/p>\n<\/li>\n<li data-start=\"1356\" data-end=\"1447\">\n<p data-start=\"1358\" data-end=\"1447\"><strong data-start=\"1358\" data-end=\"1371\">Al\u00e9rgenos<\/strong>: CRUST\u00c1CEOS, LECHE<br data-start=\"1389\" data-end=\"1392\"\/><em data-start=\"1394\" data-end=\"1447\">Puede contener rastros de: MOLUSCOS, NUCES<\/em><\/p>\n<\/li>\n<li data-start=\"1448\" data-end=\"1517\">\n<p data-start=\"1450\" data-end=\"1517\"><strong data-start=\"1450\" data-end=\"1474\">Uso recomendado<\/strong>: para pasta, \u00f1oquis, crutones, comida para comer con las manos<\/p>\n<\/li>\n<li data-start=\"1518\" data-end=\"1551\">\n<p data-start=\"1520\" data-end=\"1551\"><strong data-start=\"1520\" data-end=\"1537\">Disponibilidad<\/strong>: Todo el a\u00f1o<\/p>\n<ul>\n<li>Precio \u20ac\/kg 29,50<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><a href=\"https:\/\/salumeriaittica.org\/es\/categoria-prodotto\/ragout-y-salsas\/\">Scampi Cream 200g<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<h6>Descubre el inconfundible sabor de la Scampi Cream, una especialidad lista para usar dise\u00f1ada para realzar tus platos de marisco. Elaborada con ingredientes frescos y seleccionados, es perfecta para condimentar platos refinados \u2013 como \u00f1oquis de patata o linguini \u2013 o para servirse sobre picatostes de pan blanco para un aperitivo o buffet con un sabor refinado.<br \/>\n Precio \u20ac\/kg 29,50 <\/h6>\n","protected":false},"featured_media":21256,"comment_status":"open","ping_status":"closed","template":"","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","om_disable_all_campaigns":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"slim_seo":{"title":"Scampi Cream 200g","description":"Prueba la crema de Scampi de 200g, ideal para pasta y picatones. Producto artesanal con ingredientes frescos. Sin gluten."}},"product_brand":[],"product_cat":[2022,1518,2033,1360],"product_tag":[1419,2376,2047,2072,2115,2048,1418,2116,2046,2049,2053,2377,2052,2024,2051,2026],"class_list":["post-21245","product","type-product","status-publish","has-post-thumbnail","product_cat-ragout-y-salsas","product_cat-reserva","product_cat-reservas","product_cat-sin-gluten","product_tag-cestas-navidenas","product_tag-crema-di-scampi","product_tag-ideas-de-regalos-de-navidad","product_tag-regalos-de-navidad-3","product_tag-regalos-de-navidad-4","product_tag-regalos-de-navidad-2","product_tag-regalos-de-navidad","product_tag-regalos-de-navidad-en-amazon","product_tag-regalos-de-navidad-para-empresas","product_tag-regalos-originales-de-navidad","product_tag-reservas","product_tag-ricetta-penne-alla-crema-di-scampi","product_tag-salsa-2","product_tag-salsa-de-carne","product_tag-salsas","product_tag-sin-gluten","yith_product_brand-salsas-de-marisco","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/product\/21245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/comments?post=21245"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/media\/21256"}],"wp:attachment":[{"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/media?parent=21245"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/product_brand?post=21245"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/product_cat?post=21245"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/salumeriaittica.org\/es\/wp-json\/wp\/v2\/product_tag?post=21245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}