{"id":21681,"date":"2021-08-23T08:22:43","date_gmt":"2021-08-23T08:22:43","guid":{"rendered":"https:\/\/salumeriaittica.org\/prodotto\/mullet-bottarga\/"},"modified":"2021-08-23T08:22:43","modified_gmt":"2021-08-23T08:22:43","slug":"mullet-bottarga","status":"publish","type":"product","link":"https:\/\/salumeriaittica.org\/de\/prodotto\/mullet-bottarga\/","title":{"rendered":"Mullet Bottarga"},"content":{"rendered":"<div>\n<h1>Mullet Bottarga<\/h1>\n<p>Mullet-Rogen wird aus dem Eierstock von Fischen hergestellt, dessen Eier nach traditionellen Verfahren gesalzen und getrocknet werden.<br \/>\nDas Wort bottarga leitet sich vom arabischen bat\u0101rikh (\u062e\u0631\u0627\u0637\u0628) (&#8222;gesalzener Fischrogen&#8220;) ab.<br \/>\nDer Ursprung des Produkts scheint ph\u00f6nizisch gewesen zu sein und reicht etwa 3000 Jahre zur\u00fcck.<\/p>\n<p>Der Respekt vor der Handwerkskunst und der Nat\u00fcrlichkeit des Produkts, mit gro\u00dfem Wissen \u00fcber das Rohmaterial, kombiniert mit jahrhundertealter Erfahrung in der Verarbeitung sowie der Meeresbrise und der Mittelmeersonne, hat diesen einzigartigen Mullet-Rogen weltweit ber\u00fchmt gemacht.<br \/>\n Auf den ersten Blick bietet er einen sehr komplexen und frischen Strau\u00df: Zitrus und Jod.<\/p>\n<p>Eine seidige und samtige Textur dominiert am Gaumen,<br \/>\n Mullet-Rogen ist sehr reich an Omega-3, einem wichtigen Nahrungserg\u00e4nzungsmittel f\u00fcr Gesundheit und Sch\u00f6nheit. Aufgrund seines hohen Eiwei\u00dfgehalts war er traditionell das Gericht der Fischer, die den Tag auf See verbrachten, und heute ist er bei Gourmetk\u00f6chen und Feinschmeckern beliebt. <\/p>\n<\/div>\n<div>\n<p><a href=\"https:\/\/salumeriaittica.org\/de\/?attachment_id=7908\" rel=\"attachment wp-att-536\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7908 size-medium\" src=\"https:\/\/salumeriaittica.org\/wp-content\/uploads\/2021\/08\/bottarga-di-muggine-2-300x175.jpg\" alt=\"\" width=\"300\" height=\"175\" srcset=\"https:\/\/salumeriaittica.org\/wp-content\/uploads\/2021\/08\/bottarga-di-muggine-2-300x175.jpg 300w, https:\/\/salumeriaittica.org\/wp-content\/uploads\/2021\/08\/bottarga-di-muggine-2-500x292.jpg 500w, https:\/\/salumeriaittica.org\/wp-content\/uploads\/2021\/08\/bottarga-di-muggine-2-768x448.jpg 768w, https:\/\/salumeriaittica.org\/wp-content\/uploads\/2021\/08\/bottarga-di-muggine-2-600x350.jpg 600w, https:\/\/salumeriaittica.org\/wp-content\/uploads\/2021\/08\/bottarga-di-muggine-2.jpg 833w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<div class=\"mceTemp\"><\/div>\n<ul>\n<li>Preis \u20ac\/kg 142,80<\/li>\n<\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die Achtung der Handwerkskunst und der Nat\u00fcrlichkeit des Produkts, mit gro\u00dfem Wissen \u00fcber das Rohmaterial und jahrhundertealter Erfahrung in der Verarbeitung sowie der Meeresbrise und der mediterranen Sonne, haben diesen einzigartigen Mullet-Rogen weltweit ber\u00fchmt gemacht.<br \/>\n Das Wort bottarga stammt vom arabischen bat\u0101rikh (\u062e\u0631\u0627\u0637\u0628) (&#8222;gesalzener Fischrogen&#8220;).<br \/>\n Der Ursprung des Produkts scheint ph\u00f6nizisch und etwa 3000 Jahre zur\u00fcckreicht<br \/>\n. Preis \u20ac\/kg 145,00<\/p>\n","protected":false},"featured_media":21684,"comment_status":"open","ping_status":"closed","template":"","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","om_disable_all_campaigns":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"slim_seo":{"title":"Mullet Bottarga \u2013 \"Salumi di Mare\" aus Salumeria Ittica","description":"Mullet-Rogen besteht aus dem Eierstock des Fisches, dessen Eier gesalzen und getrocknet werden. Die Textur ist seidig und samtig"}},"product_brand":[],"product_cat":[3102,1811],"product_tag":[3103,3104,1815,2013,2016,3107,3106,3105],"class_list":["post-21681","product","type-product","status-publish","has-post-thumbnail","product_cat-bottarghe","product_cat-gepokeltes-fleisch","product_tag-bio-produkte","product_tag-bottarga","product_tag-fischdelikatessen","product_tag-gepokeltes-meeresfruchtefleisch","product_tag-glutenfrei","product_tag-mullet-roge","product_tag-sizilien","product_tag-thunfisch-bottarga","first","instock","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"_links":{"self":[{"href":"https:\/\/salumeriaittica.org\/de\/wp-json\/wp\/v2\/product\/21681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salumeriaittica.org\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/salumeriaittica.org\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/salumeriaittica.org\/de\/wp-json\/wp\/v2\/comments?post=21681"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/salumeriaittica.org\/de\/wp-json\/wp\/v2\/media\/21684"}],"wp:attachment":[{"href":"https:\/\/salumeriaittica.org\/de\/wp-json\/wp\/v2\/media?parent=21681"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/salumeriaittica.org\/de\/wp-json\/wp\/v2\/product_brand?post=21681"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/salumeriaittica.org\/de\/wp-json\/wp\/v2\/product_cat?post=21681"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/salumeriaittica.org\/de\/wp-json\/wp\/v2\/product_tag?post=21681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}