{"id":20955,"date":"2024-05-29T09:03:19","date_gmt":"2024-05-29T09:03:19","guid":{"rendered":"https:\/\/salumeriaittica.org\/prodotto\/tunin-speck\/"},"modified":"2026-08-31T15:50:36","modified_gmt":"2026-08-31T15:50:36","slug":"tunin-speck","status":"publish","type":"product","link":"https:\/\/salumeriaittica.org\/de\/prodotto\/tunin-speck\/","title":{"rendered":"TUNIN-SPECK"},"content":{"rendered":"<div>\n<h1>TUNIN-SPECK<\/h1>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Der Bauch ist das begehrteste Thunfischst\u00fcck: Der nat\u00fcrliche Geschmack von Fett passt perfekt zu den Jodnoten des Meeres, die f\u00fcr den Fisch charakteristisch sind und eines der Flaggschiffe der weltweiten Fischverarbeitung darstellen.<br \/>\n<\/span><\/span><br \/>\n<span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Seine besonderen Eigenschaften sind neben der Weichheit des Fleisches auch die W\u00fcrzung von \u00fcber drei Monaten, das Aroma der verwendeten Gew\u00fcrze sowie das zarte R\u00e4uchern aus Eichen- und Buchensp\u00e4nen aus den toskanischen Apenninen, alles kombiniert mit einer W\u00fcrzung in Zellen mit kontrollierter Luftfeuchtigkeit und Temperatur sowie dem manuellen Salzen mit Volterra-Salz.  <\/span><span style=\"vertical-align: inherit;\">Der Vakuumschneider garantiert Praktikabilit\u00e4t und hohe Ausbeute dank des hervorragenden Halts des Schnitts, der selbst sehr d\u00fcnne Scheiben erm\u00f6glicht.<\/span><\/span><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">TUNA BACON <\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"> ist ein nat\u00fcrlich verarbeitetes Produkt mit sehr hohem N\u00e4hrstoffgehalt, darunter:<\/span><\/span><\/p>\n<\/div>\n<div>\n<ul>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Hoher Proteingehalt ca. 38 %<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Reich an Omega 3 und 6, kostbare Verb\u00fcndete unseres K\u00f6rpers<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Es enth\u00e4lt viele Mineralien wie Kalium, Selen und Phosphor<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Es gibt auch B-Vitamine<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Glutenfrei<\/span><\/span><\/li>\n<li>Laktosefrei<\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Unglaublich gut und leicht.<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Geeignet f\u00fcr Sportler und Gesundheitsbegeisterte<\/span><\/span><\/li>\n<\/ul>\n<\/div>\n<div>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Reifung: 3 MONATE<\/span><\/span><\/strong><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Verpackung:<\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"> Vakuumpackung<\/span><\/span><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Nettogewicht: siehe verf\u00fcgbare Gewichte<\/span><\/span><\/strong><\/p>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Dauer: 60<\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"> Tage<\/span><\/span><\/p>\n<ul>\n<li>Preis \u20ac\/kg 107,50<\/li>\n<\/ul>\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">ALLERGENE: <\/span><\/span><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">FISCH<\/span><\/span><br \/>\n<\/strong><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><span style=\"vertical-align: inherit;\">Der Bauch ist das begehrteste Thunfischst\u00fcck: Der nat\u00fcrliche Geschmack von Fett passt perfekt zu den Jodnoten des Meeres, die f\u00fcr den Fisch charakteristisch sind und eines der Flaggschiffe der weltweiten Fischverarbeitung darstellen.<br \/>\n Preis \u20ac\/kg 107,10<\/span><\/p>\n","protected":false},"featured_media":20958,"comment_status":"open","ping_status":"closed","template":"","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","om_disable_all_campaigns":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"slim_seo":{"title":"GUANCIALE DI TONNO rosso BlUFIN \u2013 \"Salumi di Mare\"","description":"Der Blufin Bluefin Thunfisch Belly Guanciale aus Salumeria Ittica ist ein sehr feines gastronomisches Produkt, das aus der Zubereitung des mageren Filets des mediterranen Schwertfischs gewonnen und mit nat\u00fcrlicher Bel\u00fcftung gew\u00fcrzt wird. Er hat einen intensiven Geschmack; er sollte in sehr d\u00fcnne Scheiben geschnitten werden, die mit nativem Oliven\u00f6l extra gew\u00fcrzt werden."}},"product_brand":[],"product_cat":[1811,1436,1812],"product_tag":[1815,1817,1814,1813,1816],"class_list":["post-20955","product","type-product","status-publish","has-post-thumbnail","product_cat-gepokeltes-fleisch","product_cat-geraucht","product_cat-speck","product_tag-fischdelikatessen","product_tag-meerwange","product_tag-schwertfisch-fleck","product_tag-speck","product_tag-thunfischwange","yith_product_brand-meeresfruchte-gepokelte-fleisch","first","outofstock","shipping-taxable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/salumeriaittica.org\/de\/wp-json\/wp\/v2\/product\/20955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salumeriaittica.org\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/salumeriaittica.org\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/salumeriaittica.org\/de\/wp-json\/wp\/v2\/comments?post=20955"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/salumeriaittica.org\/de\/wp-json\/wp\/v2\/media\/20958"}],"wp:attachment":[{"href":"https:\/\/salumeriaittica.org\/de\/wp-json\/wp\/v2\/media?parent=20955"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/salumeriaittica.org\/de\/wp-json\/wp\/v2\/product_brand?post=20955"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/salumeriaittica.org\/de\/wp-json\/wp\/v2\/product_cat?post=20955"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/salumeriaittica.org\/de\/wp-json\/wp\/v2\/product_tag?post=20955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}